{"id":16092,"date":"2017-12-29T15:47:34","date_gmt":"2017-12-29T15:47:34","guid":{"rendered":"https:\/\/es.blogs.cam4.com\/files\/2017\/12\/cassianesexy-2.jpg"},"modified":"2017-12-29T15:47:34","modified_gmt":"2017-12-29T15:47:34","slug":"cassianesexy-2","status":"inherit","type":"attachment","link":"https:\/\/es.cam4.com\/blog\/celebra-las-cam4-xxxmas-con-los-shows-mas-especiales-del-ano-galeria-de-fotos\/cassianesexy-2\/","title":{"rendered":"cassianesexy (2)"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2.jpg'><img width=\"169\" height=\"300\" src=\"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-169x300.jpg 169w, https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-576x1024.jpg 576w, https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-600x1067.jpg 600w, https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2.jpg 675w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"attachment\"><a href='https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":675,"height":1200,"file":"2017\/12\/cassianesexy-2.jpg","sizes":{"thumbnail":{"file":"cassianesexy-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-150x150.jpg"},"medium":{"file":"cassianesexy-2-169x300.jpg","width":169,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-169x300.jpg"},"large":{"file":"cassianesexy-2-576x1024.jpg","width":576,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-576x1024.jpg"},"wysija-newsletters-max":{"file":"cassianesexy-2-600x1067.jpg","width":600,"height":1067,"mime_type":"image\/jpeg","source_url":"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2-600x1067.jpg"},"full":{"file":"cassianesexy-2.jpg","width":675,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":16000,"source_url":"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2017\/12\/cassianesexy-2.jpg","_links":{"self":[{"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/media\/16092"}],"collection":[{"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=16092"}]}}