{"id":16594,"date":"2018-02-26T18:26:22","date_gmt":"2018-02-26T18:26:22","guid":{"rendered":"https:\/\/es.blogs.cam4.com\/?p=16594"},"modified":"2018-03-06T15:19:19","modified_gmt":"2018-03-06T15:19:19","slug":"cam4-ganadora-del-premio-mejor-pagina-de-norteamerica-en-los-lalexpo-awards-2018","status":"publish","type":"post","link":"https:\/\/es.cam4.com\/blog\/cam4-ganadora-del-premio-mejor-pagina-de-norteamerica-en-los-lalexpo-awards-2018\/","title":{"rendered":"CAM4 Ganadora del premio &#8220;Mejor P\u00e1gina de Norteam\u00e9rica&#8221; en los Lalexpo Awards 2018!"},"content":{"rendered":"<h2 style=\"text-align: center;\">\u00a1\u00a1Qu\u00e9 gran semana!!<\/h2>\n<p>Esta semana tuvo lugar en la ciudad de <strong>Cali, Colombia<\/strong> la quinta edici\u00f3n de la feria <a href=\"https:\/\/lalexpo.com\/index.php\/inicio\" target=\"_blank\"><strong>Lalexpo<\/strong><\/a>, la mayor feria de negocios del sector de entreteminiento adulto de toda latinoam\u00e9rica. 3 d\u00edas llenos de actividades y oportunidades, en los que hemos podido disfrutar much\u00edsimo y muy pronto compartiremos con vosotros todos los mejores momentos!<\/p>\n<p>Pero primero queremos compartir nuestro orgullo por recibir en la gala de los<strong> Lalexpo Awards 2018<\/strong> el premio a la <strong>MEJOR P\u00c1GINA NORTEAMERICANA<\/strong> (Best North American Cam Site).<\/p>\n<p>Gracias a todos los usuarios y modelos que han votado y han hecho posible recibir este premio! Y en especial al p\u00fablico de Colombia, modelos y estudios que ayudan a hacer de la comunidad CAM4 cada d\u00eda un lugar m\u00e1s grande y divertido!<\/p>\n<p>Esperamos poder seguir siendo vuestra p\u00e1gina preferida por muchos m\u00e1s a\u00f1os!<\/p>\n<h2 style=\"text-align: center;\"><strong>\u00a1GRACIAS!<\/strong><\/h2>\n<p style=\"text-align: center;\"><a href=\"https:\/\/es.cam4.com\/blog\/files\/2018\/02\/IMG-20180222-WA0001.jpg\"><img loading=\"lazy\" class=\"aligncenter size-large wp-image-16597\" src=\"https:\/\/es.cam4.com\/blog\/files\/2018\/02\/IMG-20180222-WA0001-768x1024.jpg\" alt=\"IMG-20180222-WA0001\" width=\"768\" height=\"1024\" srcset=\"https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2018\/02\/IMG-20180222-WA0001-768x1024.jpg 768w, https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2018\/02\/IMG-20180222-WA0001-225x300.jpg 225w, https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2018\/02\/IMG-20180222-WA0001-600x800.jpg 600w, https:\/\/es.cam4.com\/blog\/wp-content\/blogs.dir\/4\/files\/2018\/02\/IMG-20180222-WA0001.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<h3 style=\"text-align: center;\">Recuerda seguir nuestras redes sociales para enterarte de todas las noticias de CAM4!<br \/>\nTwitter: <a href=\"https:\/\/twitter.com\/Cam4_ES\" target=\"_blank\">CAM4_ES<\/a><br \/>\nTwitter Gay: <a href=\"https:\/\/www.twitter.com\/Cam4_gayES\" target=\"_blank\">CAM4_GayES<\/a><br \/>\nFacebook: <a href=\"https:\/\/www.facebook.com\/CAM4.webcam.en.Espanol\" target=\"_blank\">Cam4.webcam.en.espanol<\/a><\/h3>\n<p style=\"text-align: center;\"><a class=\"xl\" href=\"https:\/\/www.cam4.com\/\">Visita CAM4 Ahora<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1\u00a1Qu\u00e9 gran semana!! <\/p>\n<p>Esta semana tuvo lugar en la ciudad de <strong>Cali, Colombia<\/strong> la quinta edici\u00f3n de la feria <a href=\"https:\/\/lalexpo.com\/index.php\/inicio\" target=\"_blank\"><strong>Lalexpo<\/strong><\/a>, la<\/p>\n","protected":false},"author":1,"featured_media":16595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5728,41028],"tags":[36,50133,32793,5611,4265,14054,74138],"_links":{"self":[{"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/16594"}],"collection":[{"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/comments?post=16594"}],"version-history":[{"count":0,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/posts\/16594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/media\/16595"}],"wp:attachment":[{"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/media?parent=16594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/categories?post=16594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.cam4.com\/blog\/wp-json\/wp\/v2\/tags?post=16594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}